{"id":2131,"date":"2026-06-25T10:31:51","date_gmt":"2026-06-25T08:31:51","guid":{"rendered":"https:\/\/popcorn-english.com\/?page_id=2131"},"modified":"2026-07-08T14:12:08","modified_gmt":"2026-07-08T12:12:08","slug":"dd","status":"publish","type":"page","link":"https:\/\/popcorn-english.com\/it\/dd\/","title":{"rendered":"DD"},"content":{"rendered":"<h2><span style=\"color: #000000;\"><strong>E&#8217; nata la nostra prima linea editoriale per bambini!<\/strong><\/span><\/h2>\n<div style=\"width: 200px; float: left; margin-right: 10px;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"http:\/\/href=&quot;https:\/\/popcorn-english.com\/en\/dd\/vol-1\/\"><img loading=\"lazy\" style=\"width: 200px;\" src=\"https:\/\/popcorn-english.com\/wp-content\/uploads\/2026\/07\/volume1-634x768.jpg\" alt=\"\" width=\"241\" height=\"292\" \/><\/a><\/span><\/div>\n<p><span style=\"color: #000000;\">Nel 2021, quando Popcorn English aveva solo due anni, ho registrato un video in cui parlavo di un sogno che avevo da tempo. Iniziava cos\u00ec:<\/span><\/p>\n<blockquote><p><span style=\"color: #000000;\"><em><strong>\u201cCredo fortemente di essere al mondo per condividere ci\u00f2 che mi appassiona con gli altri, soprattutto con i bambini: loro sono il nostro futuro!\u201d.<br \/>\n<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><em>Vanessa D.<\/em><\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400; color: #000000;\">Quel sogno era pi\u00f9 grande di una scuola di lingue.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-weight: 400;\">Immaginavo una detective, di nome DD, Detective Digoncelli, <strong>un personaggio allegro e determinato, capace di trasformare l\u2019apprendimento dell\u2019inglese in un\u2019avventura, aggiungendo divertimento, gioia e leggerezza.<\/strong><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-weight: 400;\">DD ricorda ai bambini che ogni problema richiede pazienza per essere risolto!<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400; color: #000000;\">La strada da A a B non \u00e8 sempre dritta. E&#8217; piena di curve, ostacoli e sfide, ma alla fine si arriva alla soluzione.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Quando ho condiviso questa idea con Francesca, tutto ha preso improvvisamente vita.<br \/>\n<\/strong><span style=\"font-weight: 400;\">Lei ha disegnato DD con il suo iconico impermeabile giallo, due trecce castane e i suoi caratteristici occhi a forma di maschera, e ha dato a tutto il cast le loro i<strong>nconfondibili teste a forma di popcorn<\/strong>.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400; color: #000000;\">Insieme, abbiamo trasformato una semplice idea nel <strong><span style=\"color: #ff0000;\">mondo di DD<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/popcorn-english.com\/it\/dd\/vol-1\/\">Scorpri il Volume 1!<\/a><\/span><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<h2>Per i genitori:<\/h2>\n<p><span style=\"color: #000000;\">Con la serie DD, i bambini partecipano attivamente a una storia.<\/span><br \/>\n<span style=\"color: #000000;\">Il formato mystery stimola la <strong>curiosit\u00e0<\/strong>, l\u2019<strong>attenzione<\/strong> ai dettagli e il <strong>pensiero<\/strong> autonomo.<\/span><br \/>\n<span style=\"color: #000000;\">I codici QR aggiungono <strong>contenuti audio e video per collegare l\u2019inglese scritto a quello parlato<\/strong>.<\/span><br \/>\n<span style=\"color: #000000;\">Potete supportare i bambini ponendo domande semplici come:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Che cosa \u00e8 successo in questo capitolo?<\/span><\/li>\n<li><span style=\"color: #000000;\">Chi pensi possa essere sospetto?<\/span><\/li>\n<li><span style=\"color: #000000;\">Quale indizio hai trovato?<\/span><\/li>\n<\/ul>\n<hr \/>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #000000;\">Le autrici:<\/span><\/h2>\n<p><span style=\"color: #000000;\"><strong>Vanessa Digoncelli<\/strong><\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #000000;\">Laurea in Lingue, Letterature Straniere e Studi Interculturali\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #000000;\">CELTA, Cambridge University<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #000000;\">Insegnante di lingue straniere specializzata nella fascia d&#8217;et\u00e0 4\u201316 anni<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\"><strong>Francesca Damiano<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Visual Designer &amp; esperta in Mktg e Comunicazione<\/span><\/li>\n<li><span style=\"color: #000000;\">Executive Master in Neuromarketing<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; nata la nostra prima linea editoriale per bambini! Nel 2021, quando Popcorn English aveva solo due anni, ho registrato un video in cui parlavo di un sogno che avevo da tempo. Iniziava cos\u00ec: \u201cCredo fortemente di essere al mondo per condividere ci\u00f2 che mi appassiona con gli altri, soprattutto con i bambini: loro sono [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DD | Pop Corn English<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/popcorn-english.com\/it\/dd\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DD | Pop Corn English\" \/>\n<meta property=\"og:description\" content=\"E&#8217; nata la nostra prima linea editoriale per bambini! Nel 2021, quando Popcorn English aveva solo due anni, ho registrato un video in cui parlavo di un sogno che avevo da tempo. Iniziava cos\u00ec: \u201cCredo fortemente di essere al mondo per condividere ci\u00f2 che mi appassiona con gli altri, soprattutto con i bambini: loro sono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/popcorn-english.com\/it\/dd\/\" \/>\n<meta property=\"og:site_name\" content=\"Pop Corn English\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:12:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/popcorn-english.com\/wp-content\/uploads\/2026\/07\/volume1-634x768.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\">\n\t<meta name=\"twitter:data1\" content=\"Vanessa Digoncelli\">\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\">\n\t<meta name=\"twitter:data2\" content=\"1 minuto\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/popcorn-english.com\/it\/#website\",\"url\":\"https:\/\/popcorn-english.com\/it\/\",\"name\":\"Popcorn English\",\"description\":\"Lezioni per bambini, adulti e aziende. Camp estivi e gite alla scoperta del Ticino. Servizio di babysitting didattico, doposcuola\\u2026 e tanto altro!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/popcorn-english.com\/it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/popcorn-english.com\/it\/dd\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/popcorn-english.com\/wp-content\/uploads\/2026\/07\/volume1.jpg\",\"width\":754,\"height\":913},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/popcorn-english.com\/it\/dd\/#webpage\",\"url\":\"https:\/\/popcorn-english.com\/it\/dd\/\",\"name\":\"DD | Pop Corn English\",\"isPartOf\":{\"@id\":\"https:\/\/popcorn-english.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/popcorn-english.com\/it\/dd\/#primaryimage\"},\"datePublished\":\"2026-06-25T08:31:51+00:00\",\"dateModified\":\"2026-07-08T12:12:08+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/popcorn-english.com\/it\/dd\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/popcorn-english.com\/it\/wp-json\/wp\/v2\/pages\/2131\/"}],"collection":[{"href":"https:\/\/popcorn-english.com\/it\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/popcorn-english.com\/it\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/popcorn-english.com\/it\/wp-json\/wp\/v2\/users\/2\/"}],"replies":[{"embeddable":true,"href":"https:\/\/popcorn-english.com\/it\/wp-json\/wp\/v2\/comments\/?post=2131"}],"version-history":[{"count":14,"href":"https:\/\/popcorn-english.com\/it\/wp-json\/wp\/v2\/pages\/2131\/revisions\/"}],"predecessor-version":[{"id":2598,"href":"https:\/\/popcorn-english.com\/it\/wp-json\/wp\/v2\/pages\/2131\/revisions\/2598\/"}],"wp:attachment":[{"href":"https:\/\/popcorn-english.com\/it\/wp-json\/wp\/v2\/media\/?parent=2131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}